{"id":1806,"date":"2019-03-15T20:39:58","date_gmt":"2019-03-15T19:39:58","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/gesundheitsbrunch-alles-zu-natur-und-gesundheit\/"},"modified":"2019-10-17T10:09:23","modified_gmt":"2019-10-17T08:09:23","slug":"gesundheitsbrunch-alles-zu-natur-und-gesundheit","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/gesundheitsbrunch-alles-zu-natur-und-gesundheit\/","title":{"rendered":"Gesundheitsbrunch &#8211; alles zu Natur und Gesundheit am 7. April"},"content":{"rendered":"<p>Die Gesunde Gemeinde Ferschnitz l\u00e4dt ein zum Gesundheitsbrunch am 7. April von 10.00 bis 15.00 Uhr im Mehrzwecksaal Ferschnitz<\/p>\n<p><\/p>\n<p>Aussteller und Informationen,<br \/>Saatgut- und Pflanzentauschmarkt (Tauschen Sie Ihre eignen Pflanzen)<br \/>gesunde Jause,<br \/>Fairtrade Kaffee und Kuchen.<\/p>\n<p>Vortr\u00e4ge:<\/p>\n<ul>\n<li>11:00 Dr. Paumann: \u201cFit ein Leben lang\u201d<br \/>12:00 Bernhard Haidler von Natur im Garten: \u201cQuer durchs Gem\u00fcsebeet\u201d<br \/>13:00 Alexandra Haas-Steinwendner von Pure EnerQi: \u201cHanf \u2013 Volksmedizin des 21. Jahrhunderts?\u201d<br \/>14:00 Doris Fahrnberger: \u201cGedankenhygiene \u2013 Was ist das?\u201d<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Gesunde Gemeinde Ferschnitz l\u00e4dt ein zum Gesundheitsbrunch am 7. April von 10.00 bis 15.00 Uhr im Mehrzwecksaal Ferschnitz Aussteller und Informationen,Saatgut- und Pflanzentauschmarkt (Tauschen Sie Ihre eignen Pflanzen)gesunde Jause,Fairtrade Kaffee und Kuchen. Vortr\u00e4ge: 11:00 Dr. Paumann: \u201cFit<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/gesundheitsbrunch-alles-zu-natur-und-gesundheit\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":18,"featured_media":1825,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,35,37,30],"tags":[],"class_list":["post-1806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-alle-gemeinden","category-lebensbereiche","category-ferschnitz"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/1806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=1806"}],"version-history":[{"count":1,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/1806\/revisions"}],"predecessor-version":[{"id":1827,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/1806\/revisions\/1827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/1825"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=1806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=1806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=1806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}