{"id":383,"date":"2018-03-05T08:20:41","date_gmt":"2018-03-05T07:20:41","guid":{"rendered":"http:\/\/www.donau-ybbsfeld.at\/blog\/?p=383"},"modified":"2019-10-17T10:16:48","modified_gmt":"2019-10-17T08:16:48","slug":"ardagger-im-gehspraech","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/ardagger-im-gehspraech\/","title":{"rendered":"Ardagger im GEHspr\u00e4ch"},"content":{"rendered":"<p>Gef\u00fchrter Spaziergang am 8. September 2018, 14.00 Uhr<\/p>\n<p>Treffpunkt: Gemeindeamt Ardagger, Markt 55, 3321 Ardagger Markt<\/p>\n<p>Wegstrecke ca. 3 km<\/p>\n<p>&nbsp;<\/p>\n<p><strong>GEHsp<\/strong><strong>r\u00e4chsleiter: Martin R\u00fchrnschopf, Architekt<\/strong><\/p>\n<p>Eingebettet zwischen Donau und Mostviertler H\u00fcgelland liegen die Katastralgemeinden Ardagger Markt, Ardagger Stift, Kollmitzberg und Stephanshart, die in der Marktgemeinde Ardagger administrativ vereint sind und trotzdem ihre Vielfalt wie Eigenst\u00e4ndigkeit bewahrt haben. Von den vier Gemeinden f\u00e4llt Ardagger Markt besonders ins Auge, liegt sie doch etwas eingeschn\u00fcrt zwischen dem Hochwasserschutzdamm mit der B119 und dem Hang. Sie zeichnet sich durch eine intakte Infrastruktur im \u201eAltort\u201c und den neuen Ortsteil &#8211; der Sonnensiedlung &#8211; in attraktiver Hanglage aus. Doch auch in Ardagger Markt stellen sich \u2013 wie vielerorts &#8211; Herausforderungen im richtigen Umgang mit Leerstand oder Unterbelegung, Fl\u00e4chenverwertung und Verkehrsaufkommen, f\u00fcr die L\u00f6sungen anstehen.<\/p>\n<p>Ein GEHspr\u00e4ch im Sinne der \u201eSpaziergangswissenschaft\u201c, die der Schweizer Soziologe Lucius Burckhardt erfunden hat, f\u00fchrt durch den alten wie neuen Ort und bietet die M\u00f6glichkeit, die Siedlungsentwicklung einst und jetzt gemeinsam zu reflektieren. Die Bewohner aus Ardagger sowie Interessierte aus den Nachbargemeinden sind herzlich eingeladen, den Ort im gemeinsamen Gehen, Betrachten und miteinander Sprechen zu erkunden.<\/p>\n<p>Abschlie\u00dfend werden im Gasthaus St\u00f6ger und anschlie\u00dfend vielleicht noch im &#8222;PapperlaPUB&#8220; die Wahrnehmungen des Lebensraums Ardagger Markt gemeinsam reflektiert. &#8211; Im Idealfall entstehen neue Ideen, die dazu f\u00fchren k\u00f6nnen, die Gemeinde und den Ort noch lebendiger und lebenswerter zu gestalten.<\/p>\n<p>Anmeldung erbeten unter <a href=\"mailto:office@orte-noe.at\">office@orte-noe.at<\/a><\/p>\n<p>Die Teilnahme am GEHspr\u00e4ch ist kostenlos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gef\u00fchrter Spaziergang am 8. September 2018, 14.00 Uhr Treffpunkt: Gemeindeamt Ardagger, Markt 55, 3321 Ardagger Markt Wegstrecke ca. 3 km &nbsp; GEHspr\u00e4chsleiter: Martin R\u00fchrnschopf, Architekt Eingebettet zwischen Donau und Mostviertler H\u00fcgelland liegen die Katastralgemeinden Ardagger Markt, Ardagger Stift,<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/ardagger-im-gehspraech\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":14,"featured_media":386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,29],"tags":[],"class_list":["post-383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-ardagger"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":2,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/383\/revisions"}],"predecessor-version":[{"id":388,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/383\/revisions\/388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/386"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}