{"id":4746,"date":"2020-06-16T10:02:06","date_gmt":"2020-06-16T08:02:06","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=4746"},"modified":"2020-06-16T10:07:49","modified_gmt":"2020-06-16T08:07:49","slug":"ferienprogramm-sommererlebnis-kleinregion-donau-ybbsfeld","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/ferienprogramm-sommererlebnis-kleinregion-donau-ybbsfeld\/","title":{"rendered":"Ferienprogramm &#8222;Sommererlebnis Kleinregion Donau-Ybbsfeld&#8220;"},"content":{"rendered":"<p>Bei der Arbeitssitzung der SozialkoordinatorInnen der Kleinregion Donau-Ybbsfeld Ende Mai 2020 wurden im Georgsaal in St. Georgen \/ Ybbsfelde Pl\u00e4ne f\u00fcr einen gemeinsamen Prospekt aller 7 Partnergemeinden \u00fcber sehenswerte Ausflugsziele innerhalb der Kleinregion geschmiedet und in der folgenden Woche gleich umgesetzt. Das so entstandene Programm \u201eSommererlebnis Kleinregion Donau-Ybbsfeld\u201c hebt den \u00fcberw\u00e4ltigenden Charme unserer Kleinregion hervor und bietet f\u00fcr den heurigen Sommer zahlreiche, familiengerechte Attraktionen in der nahen Umgebung, die sicher einen Besuch wert sind. In diesen Tagen ergeht dieser abwechslungsreiche Ausflugs-Ratgeber an alle rund 16.000 Haushalte der Kleinregion, durch Ver\u00f6ffentlichung in den jeweiligen Gemeindezeitungen.<\/p>\n<p>Du kannst das \u201eSommererlebnis Kleinregion Donau-Ybbsfeld\u201c entweder aus deiner Gemeindezeitung zur weiteren Verwendung und einfacheren Planung deiner Ausfl\u00fcge entnehmen oder dir \u00fcber untenstehenden Link selbst ausdrucken. <\/p>\n<p>Wir w\u00fcnschen allen einen erlebnisreichen und erholsamen Sommer in unserer wundersch\u00f6nen Kleinregion!<br \/>\nEure SozialkoordinatorInnen der 7 Partnergemeinden<\/p>\n<p><b><a href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-content\/uploads\/sommer_2020_KR_Donau_Ybbsfeld.pdf\" rel=\"noopener noreferrer\" target=\"_blank\">Download Programm Sommer 2020 der Kleinregion &#8222;Donau-Ybbsfeld&#8220;<\/a><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei der Arbeitssitzung der SozialkoordinatorInnen der Kleinregion Donau-Ybbsfeld Ende Mai 2020 wurden im Georgsaal in St. Georgen \/ Ybbsfelde Pl\u00e4ne f\u00fcr einen gemeinsamen Prospekt aller 7 Partnergemeinden \u00fcber sehenswerte Ausflugsziele innerhalb der Kleinregion geschmiedet und in der folgenden<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/ferienprogramm-sommererlebnis-kleinregion-donau-ybbsfeld\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":4747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,29,28,30,63,6,32,65,34,33,31],"tags":[],"class_list":["post-4746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-ardagger","category-blindenmarkt","category-ferschnitz","category-freizeit","category-gesundheit","category-neustadtl-an-der-donau","category-sport-spiel","category-st-georgen-am-ybbsfelde","category-st-martin-karlsbach","category-viehdorf"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/4746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=4746"}],"version-history":[{"count":3,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/4746\/revisions"}],"predecessor-version":[{"id":4771,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/4746\/revisions\/4771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/4747"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=4746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=4746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=4746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}