{"id":5662,"date":"2021-12-13T17:17:43","date_gmt":"2021-12-13T16:17:43","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=5662"},"modified":"2021-12-13T17:26:11","modified_gmt":"2021-12-13T16:26:11","slug":"neue-online-plattform-rund-um-pflege-www-pflege-gv-at","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/neue-online-plattform-rund-um-pflege-www-pflege-gv-at\/","title":{"rendered":"Neue online-Plattform rund um Pflege: www.pflege.gv.at"},"content":{"rendered":"<p>Die neue online-Plattform wurde im Auftrag des Sozialministeriums durch die Gesundheit \u00d6sterreich GmbH erstellt. Zweck ist es f\u00fcr Interessenten, Pflegebed\u00fcrftige und deren Angeh\u00f6rige, besonders \u00fcbersichtliche und leicht zug\u00e4ngliche Informationen rund ums Thema Pflege &amp; Betreuung zur Verf\u00fcgung zu stellen: <a href=\"http:\/\/www.pflege.gv.at\" target=\"_blank\" rel=\"noopener\"><strong>www.pflege.gv.at<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die neue online-Plattform wurde im Auftrag des Sozialministeriums durch die Gesundheit \u00d6sterreich GmbH erstellt. Zweck ist es f\u00fcr Interessenten, Pflegebed\u00fcrftige und deren Angeh\u00f6rige, besonders \u00fcbersichtliche und leicht zug\u00e4ngliche Informationen rund ums Thema Pflege &amp; Betreuung zur Verf\u00fcgung zu<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/neue-online-plattform-rund-um-pflege-www-pflege-gv-at\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":5663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,4,28,6,66,7],"tags":[],"class_list":["post-5662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-beratung","category-blindenmarkt","category-gesundheit","category-pflege","category-selbsthilfe-soziale-netzwerke"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=5662"}],"version-history":[{"count":3,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5662\/revisions"}],"predecessor-version":[{"id":5667,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5662\/revisions\/5667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/5663"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=5662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=5662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=5662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}