{"id":5827,"date":"2022-05-14T17:41:35","date_gmt":"2022-05-14T15:41:35","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=5827"},"modified":"2022-05-14T19:27:10","modified_gmt":"2022-05-14T17:27:10","slug":"neuer-sommerflyer-der-gesunden-kleinregion-donau-ybbsfeld","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/neuer-sommerflyer-der-gesunden-kleinregion-donau-ybbsfeld\/","title":{"rendered":"Neuer Sommerflyer der Gesunden Kleinregion Donau-Ybbsfeld"},"content":{"rendered":"<p>Die Kleinregion Donau-Ybbsfeld widmet ihren heurigen Sommerflyer dem wichtigen Thema \u201eGesundheit &amp; mehr\u201c. Wie in den Jahren zuvor, r\u00fcckt die Kleinregion damit die vielen Angebote und wertvollen Ressourcen in ihren 6 Partnergemeinden Ardagger, Blindenmarkt, Ferschnitz, Neustadtl, St. Georgen am Ybbsfelde und Viehdorf zu einem ausgew\u00e4hlten Schwerpunkt-Thema in den Vordergrund. Seit Dezember 2021 ist die Kleinregion Donau-Ybbsfeld nicht nur \u201eFamilienfreundliche Region\u201c sondern nunmehr auch \u201eGesunde Kleinregion\u201c. Damit lag es nahe, den neuen Sommerflyer der Angebotsvielfalt in den Partnergemeinden im Bereich \u201eGesundheit &amp; mehr\u201c zu widmen. Rund 25 Betriebe mit schulmedizinisch-\u00e4rztlichem Bezug und \u00fcber 75 Unternehmen aus verschiedensten therapeutischen Fachdisziplinen, aber auch Alternativ-Medizin, Kosmetik, etc. sind darin als kompakter \u00dcberblick zusammengestellt. F\u00fcr die kommenden Jahre ist geplant, noch mehr gemeinsame Projekte der Gesundheitsf\u00f6rderung in der Gesunden Kleinregion Donau-Ybbsfeld umzusetzen \u2013 der Sommerflyer \u201eGesundheit &amp; mehr\u201c ist zur Erhebung des vorhandenen Angebots in den 6 Gemeinden ein erster Schritt dazu.<\/p>\n<p>In den Jahren 2020 und 2021 wurden die Themen \u201eAusflugsziele der Kleinregion\u201c sowie \u201eRegionalvermarkter der Kleinregion\u201c im Sommerflyer f\u00fcr die B\u00fcrgerinnen und B\u00fcrger umfassend zusammengestellt \u2013 immer zum Herausnehmen als Mittelteil der jeweiligen Gemeindezeitungen. Wir w\u00fcnschen viel Freude beim Entdecken der vielf\u00e4ltigen Angebote in unserem kleinregionalen Sommerprospekt 2022.<\/p>\n<h5 class=\"Default\"><span style=\"font-size: 10.0pt;\">Foto (\u00a9 KR Donau-Ybbsfeld) vlnr vorne: BGM Franz Wurzer, BGM Michael H\u00fclmbauer, BGM Johannes Pressl, BGM Franz Kriener, BGM Christoph Haselsteiner, vlnr dahinter: GGR Anita Pitzl, GGR Michaela Salzmann-Naderer, GGR Karin Ebner, Vize-BGM Franz Eder, GGR Edith Weichinger, GR Simone Hofbauer, GR Anita Hagler, Vize-BGM Lukas Zeilinger<\/span><\/h5>\n<p><a href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-content\/uploads\/gesundheitsangebot_kleinregion_2022_A3.pdf\" rel=\"noopener\" target=\"_blank\"><strong>>> Download Sommerflyer &#8222;Gesundheit &#038; Mehr&#8220;<\/strong><\/a><\/p>\n<a href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-content\/uploads\/gesundheitsangebot_kleinregion_2022_A4.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">gesundheitsangebot_kleinregion_2022_A4<\/a>\n","protected":false},"excerpt":{"rendered":"<p>Die Kleinregion Donau-Ybbsfeld widmet ihren heurigen Sommerflyer dem wichtigen Thema \u201eGesundheit &amp; mehr\u201c. Wie in den Jahren zuvor, r\u00fcckt die Kleinregion damit die vielen Angebote und wertvollen Ressourcen in ihren 6 Partnergemeinden Ardagger, Blindenmarkt, Ferschnitz, Neustadtl, St. Georgen<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/neuer-sommerflyer-der-gesunden-kleinregion-donau-ybbsfeld\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":5828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,35,4,63,6],"tags":[],"class_list":["post-5827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-alle-gemeinden","category-beratung","category-freizeit","category-gesundheit"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=5827"}],"version-history":[{"count":5,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5827\/revisions"}],"predecessor-version":[{"id":5835,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5827\/revisions\/5835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/5828"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=5827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=5827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=5827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}