{"id":5936,"date":"2022-06-20T14:19:06","date_gmt":"2022-06-20T12:19:06","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=5936"},"modified":"2022-07-05T08:04:37","modified_gmt":"2022-07-05T06:04:37","slug":"fitfresh-fitness-am-ausee-im-juli","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/fitfresh-fitness-am-ausee-im-juli\/","title":{"rendered":"FIT&#038;fresh Fitness am Ausee im Juli"},"content":{"rendered":"<p>Es sind noch 5 Pl\u00e4tze frei &#8211; wir freuen uns ebenso \u00fcber TeilnehmerInnen aus den Nachbargemeinden! Kinder d\u00fcrfen gerne mitgenommen werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es sind noch 5 Pl\u00e4tze frei &#8211; wir freuen uns ebenso \u00fcber TeilnehmerInnen aus den Nachbargemeinden! Kinder d\u00fcrfen gerne mitgenommen werden.<\/p>\n","protected":false},"author":2,"featured_media":5937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,63,6,1,65],"tags":[],"class_list":["post-5936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blindenmarkt","category-freizeit","category-gesundheit","category-interne-beitraege","category-sport-spiel"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=5936"}],"version-history":[{"count":1,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5936\/revisions"}],"predecessor-version":[{"id":5938,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/5936\/revisions\/5938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/5937"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=5936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=5936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=5936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}