{"id":6328,"date":"2023-05-04T18:08:20","date_gmt":"2023-05-04T16:08:20","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=6328"},"modified":"2023-05-04T18:08:20","modified_gmt":"2023-05-04T16:08:20","slug":"planungssitzung-der-gesunden-kleinregion-donau-ybbsfeld-in-neustadtl-a-d-donau","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/planungssitzung-der-gesunden-kleinregion-donau-ybbsfeld-in-neustadtl-a-d-donau\/","title":{"rendered":"Planungssitzung der Gesunden Kleinregion Donau-Ybbsfeld in Neustadtl a.d. Donau"},"content":{"rendered":"<p>Die Sch\u00e4tze der Gesunden Kleinregion Donau-Ybbsfeld den eigenen Partnergemeinden (Ardagger, Blindenmarkt, Ferschnitz, Neustadtl a.d. Donau, St. Georgen am Ybbsfelde und Viehdorf) sichtbar zu machen, ist unter anderem ein wichtiges Ziel der SozialsprecherInnen aus der Kleinregion. Diesmal fand auf Einladung die Planungssitzung in Neustadtl an der Donau statt. <\/p>\n<p>Dabei ergab sich die Gelegenheit dem jungen Regionalvermarkter \u201eRegionalstadl\u201c f\u00fcr Verkostungen regionaler Produkte vor Ort einen Besuch abzustatten. In der anschlie\u00dfenden Gespr\u00e4chsrunde im Neustadtler Jakobsaal wurden neben R\u00fcckblicken zu vergangenen Veranstaltungen, wie zB. den Achtsamkeits-Workshop im M\u00e4rz 2023, auch Pl\u00e4ne f\u00fcr den Sommer und Herbst 2023 geschmiedet. So waren das Sommerangebot der Gemeinden f\u00fcr ihre B\u00fcrgerInnen ein wichtiges Thema, aber auch das Konzept f\u00fcr ein regionales Kochbuch mit Rezepten aus der Kleinregion. Auch fand sich Zeit f\u00fcr den wichtigen Austausch zwischen den anwesenden GemeindevertreterInnen der Gesunden Kleinregion Donau-Ybbsfeld, um Synergien bei der Erstellung von k\u00fcnftigen Gesundheits-Angeboten f\u00fcr alle Bewohner der Kleinregion gezielt abzustimmen und zu nutzen. <\/p>\n<p>Besonders der gemeinsame Blog der Kleinregion unter <a href=\"http:\/\/blog.donau-ybbsfeld.at\" rel=\"noopener\" target=\"_blank\">blog.donau-ybbsfeld.at<\/a>, der von allen sechs Partnergemeinden mit der laufenden Ver\u00f6ffentlichung der vielen gemeinde\u00fcbergreifenden Gesundheitsangebote gepflegt wird, erfreut sich steigender Besucherzahlen. Moderatorin des Abends und Sozialsprecherin der Kleinregion, Karin Ebner stellte abschlie\u00dfend fest: \u201eEs war eine wirklich erfolgreiche Zusammenkunft unserer SozialreferentInnen aus der Kleinregion. Wir konnten stolz feststellen, wie viel bereits f\u00fcr die Gesundheit unserer B\u00fcrgerInnen in unseren Partnergemeinden umgesetzt wird \u2013 das erh\u00f6ht nat\u00fcrlich den Anreiz f\u00fcr Verbesserungen und k\u00fcnftige Angebote.\u201c<\/p>\n<p>Foto (\u00a9 Kleinregion Donau-Ybbsfeld) vlnr: BGM Michael H\u00fclmbauer (Ferschnitz), Gerald Wagner und Nicole Pils mit ihren beiden Kindern, GR Claudia Furtner, GGR Edith Weichinger, GR Johannes Wagner (alle 3 Neustadtl, Vize-BGM Franz Eder (Viehdorf), GGR Anita Pitzl (Blindenmarkt), GR Gerlinde Jochinger (St. Georgen\/Y.), BGM Franz Kriener (Neustadtl), GGR Maria Seisenbacher (Viehdorf), Kleinregions-Sozialsprecherin Karin Ebner, GR Karin Gr\u00fcnberger, BGM Christoph Haselsteiner (alle 3 aus St. Georgen\/Y.) Kleinregions-Sprecher BGM Johannes Pressl (Ardagger)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Sch\u00e4tze der Gesunden Kleinregion Donau-Ybbsfeld den eigenen Partnergemeinden (Ardagger, Blindenmarkt, Ferschnitz, Neustadtl a.d. Donau, St. Georgen am Ybbsfelde und Viehdorf) sichtbar zu machen, ist unter anderem ein wichtiges Ziel der SozialsprecherInnen aus der Kleinregion. Diesmal fand auf<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/planungssitzung-der-gesunden-kleinregion-donau-ybbsfeld-in-neustadtl-a-d-donau\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":6329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,35,37,32],"tags":[],"class_list":["post-6328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-alle-gemeinden","category-lebensbereiche","category-neustadtl-an-der-donau"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=6328"}],"version-history":[{"count":1,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6328\/revisions"}],"predecessor-version":[{"id":6330,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6328\/revisions\/6330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/6329"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=6328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=6328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=6328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}