{"id":6766,"date":"2024-02-24T21:55:05","date_gmt":"2024-02-24T20:55:05","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=6766"},"modified":"2024-02-24T22:08:35","modified_gmt":"2024-02-24T21:08:35","slug":"umfangreiches-programm-fuer-2024-bei-kleinregions-treffen-in-viehdorf-festgelegt","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/umfangreiches-programm-fuer-2024-bei-kleinregions-treffen-in-viehdorf-festgelegt\/","title":{"rendered":"Umfangreiches Programm f\u00fcr 2024 bei Kleinregions-Treffen in Viehdorf festgelegt"},"content":{"rendered":"<p>Beim diesmaligen Treffen der Sozialkoordinatoren der Kleinregion Donau-Ybbsfeld wurde vom Team &#8211; dankenswerterweise begleitet von ausf\u00fchrlichen Erkl\u00e4rungen des Viehdorfer B\u00fcrgermeisters Franz Zehethofer &#8211; die neue Ordination von Dr. Bettina Rathgeb in Hainstetten besichtigt.<\/p>\n<p>In der anschlie\u00dfenden, von Sozialsprecherin Karin Ebner (St. Georgen) geleiteten Zusammenkunft der anwesenden Gemeindevertreter, kamen unter anderem die Themen Ferienbetreuung sowie die Inhalte des mittlerweile umfangreichen Sommerferien-Programms zur Sprache. Auch heuer wird es erfreulicherweise wieder zahlreiche Angebote in den Ferien f\u00fcr die j\u00fcngeren B\u00fcrger der Kleinregion geben. Ebenso beabsichtigen die sechs Partnergemeinden im Herbst bei einem gemeinsamen &#8222;Kindertag&#8220; im St. Georgner Georgsaal, die interessierten Besucher zu Angeboten rund um Ern\u00e4hrung, Bewegung und mentaler Gesundheit f\u00fcr die Kinder unserer Kleinregion zu begr\u00fc\u00dfen.<\/p>\n<p>Weiters wurde die gegenseitige Zusammenarbeit und Unterst\u00fctzung bei der Zertifizierung f\u00fcr die Tut-Gut-F\u00f6rderstufen vereinbart und die weiteren zu f\u00f6rdernden Projekte, wie ein Selbstverteidigungskurs f\u00fcr Jugendliche, ein Vortrag zur Darmgesundheit, Yoga am Fluss und zwei Achtsamkeits-Workshops f\u00fcr dieses Jahr festgelegt. &#8222;Auch die Bewerbung des Kochbuchs der Kleinregion zu Muttertag sowie die k\u00fcnftige Abhaltung von Pflegestammtischen in den Partnergemeinden, sind wichtige Umsetzungen der Kleinregion Donau-Ybbsfeld&#8220;, so Sozialsprecherin Karin Ebner abschlie\u00dfend.<\/p>\n<p>Foto (\u00a9 Kleinregion Donau-Ybbsfeld) vlnr stehend: GGR Maria Seisenbacher ( Viehdorf), Vize-BGM Anita Pitzl (Blindenmarkt), GR Anita Hagler (Ardagger), GGR Edith Weichinger (Neustadtl), Sozialsprecherin Karin Ebner, GR Gerlinde Jochinger (beide St. Georgen \/ Ybbsfelde), sitzend vlnr: Vize-BGM Franz Eder (Viehdorf), GGR Michaela Salzmann-Naderer (Ardagger), GR Simone Hofbauer, GR Christa Fischer (beide Neustadtl), Kleinregionssprecher BGM Johannes Pressl (Ardagger), BGM Franz Zehethofer (Viehdorf)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim diesmaligen Treffen der Sozialkoordinatoren der Kleinregion Donau-Ybbsfeld wurde vom Team &#8211; dankenswerterweise begleitet von ausf\u00fchrlichen Erkl\u00e4rungen des Viehdorfer B\u00fcrgermeisters Franz Zehethofer &#8211; die neue Ordination von Dr. Bettina Rathgeb in Hainstetten besichtigt. In der anschlie\u00dfenden, von Sozialsprecherin<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/umfangreiches-programm-fuer-2024-bei-kleinregions-treffen-in-viehdorf-festgelegt\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":6769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,37,31],"tags":[],"class_list":["post-6766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-altersgruppen","category-lebensbereiche","category-viehdorf"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=6766"}],"version-history":[{"count":10,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6766\/revisions"}],"predecessor-version":[{"id":6780,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6766\/revisions\/6780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/6769"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=6766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=6766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=6766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}