{"id":6813,"date":"2024-03-20T14:40:17","date_gmt":"2024-03-20T13:40:17","guid":{"rendered":"https:\/\/www.donau-ybbsfeld.at\/blog\/?p=6813"},"modified":"2024-03-21T07:45:19","modified_gmt":"2024-03-21T06:45:19","slug":"familien-und-beratungszentrum-amstetten-familienberatungsstelle","status":"publish","type":"post","link":"https:\/\/www.donau-ybbsfeld.at\/blog\/familien-und-beratungszentrum-amstetten-familienberatungsstelle\/","title":{"rendered":"Familien- und Beratungszentrum Amstetten &#8211; Familienberatungsstelle"},"content":{"rendered":"\r\n<h1 class=\"headline_special-margin\">Familien- und Beratungszentrum Amstetten &#8211; Hilfswerk Nieder\u00f6sterreich<\/h1>\r\n<h2>Alles aus einer Hand: Wir sind f\u00fcr Sie und Ihre Familie da!<\/h2>\r\n<p>Im Familien- und Beratungszentrum Amstetten finden Sie alle Angebote rund um Kinderbetreuung, Lerntraining, Beratung in allen Lebenssituationen und Psychotherapie geb\u00fcndelt. Auch f\u00fcr vielf\u00e4ltige Bildungsangebote sind wir der richtige Ansprechpartner.<br \/><br \/>Kinderbetreuung durch unsere (mobilen) Tagesm\u00fctter\/-v\u00e4ter<br \/>Kinderbetreuung in unseren Einrichtungen<br \/>Kompetentes Lerntraining<br \/>Eltern-Kind-Zentrum: Alles f\u00fcr die Familie<br \/>Beratung in allen Lebenssituationen<br \/>Psychotherapie f\u00fcr Kinder, Jugendliche &amp; Erwachsene<br \/><br \/><strong><a href=\"https:\/\/www.hilfswerk.at\/niederoesterreich\/wir-ueber-uns\/unsere-standorte\/standorte-familien-und-beratungszentren\/familien-und-beratungszentrum-amstetten\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.hilfswerk.at\/niederoesterreich\/wir-ueber-uns\/unsere-standorte\/standorte-familien-und-beratungszentren\/familien-und-beratungszentrum-amstetten\/<\/a><\/strong><br \/><br \/><strong><a href=\"https:\/\/www.hilfswerk.at\/niederoesterreich\/wir-ueber-uns\/kontakt-familien-und-beratungszentrum\/kontaktformular-fbz-amstetten\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.hilfswerk.at\/niederoesterreich\/wir-ueber-uns\/kontakt-familien-und-beratungszentrum\/kontaktformular-fbz-amstetten\/<\/a><\/strong><\/p>\r\n<p><strong><a href=\"https:\/\/www.hilfswerk.at\/niederoesterreich\/familie-beratung\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.hilfswerk.at\/niederoesterreich\/familie-beratung\/<\/a><\/strong><\/p>\r\n<p>&nbsp;<\/p>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Familien- und Beratungszentrum Amstetten &#8211; Hilfswerk Nieder\u00f6sterreich Alles aus einer Hand: Wir sind f\u00fcr Sie und Ihre Familie da! Im Familien- und Beratungszentrum Amstetten finden Sie alle Angebote rund um Kinderbetreuung, Lerntraining, Beratung in allen Lebenssituationen und Psychotherapie<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.donau-ybbsfeld.at\/blog\/familien-und-beratungszentrum-amstetten-familienberatungsstelle\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":26,"featured_media":6820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5,28,6,22,20,19,21],"tags":[],"class_list":["post-6813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beratung","category-betreuung","category-blindenmarkt","category-gesundheit","category-jugendliche","category-kindergartenkind","category-kleinkind-bis-3-jahre","category-schuelerin"],"_links":{"self":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/comments?post=6813"}],"version-history":[{"count":5,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6813\/revisions"}],"predecessor-version":[{"id":6824,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/posts\/6813\/revisions\/6824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media\/6820"}],"wp:attachment":[{"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/media?parent=6813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/categories?post=6813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donau-ybbsfeld.at\/blog\/wp-json\/wp\/v2\/tags?post=6813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}